{"id":11034,"date":"2026-03-27T13:58:21","date_gmt":"2026-03-27T12:58:21","guid":{"rendered":"https:\/\/puycapel.fr\/?p=11034"},"modified":"2026-03-27T14:57:50","modified_gmt":"2026-03-27T13:57:50","slug":"vente-dherbe","status":"publish","type":"post","link":"https:\/\/puycapel.fr\/index.php\/2026\/03\/27\/vente-dherbe\/","title":{"rendered":"Vente d&rsquo;herbe"},"content":{"rendered":"\n<p><strong>LA COMMUNE DE PUYCAPEL<\/strong><\/p>\n\n\n\n<p>Propose 2 lots de vente d\u2019herbe&nbsp;: environ 6 Ha chacun.<\/p>\n\n\n\n<p><strong><u>Un cahier des charges a \u00e9t\u00e9 \u00e9tabli par le conseil municipal&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<p>2 lots disponibles pour 2 exploitations diff\u00e9rentes\/<\/p>\n\n\n\n<p><strong><em>PRIORITE 1&nbsp;:<\/em><\/strong> si\u00e8ge d\u2019exploitation et au moins un des exploitants habitant sur la commune de PUYCAPEL<\/p>\n\n\n\n<p><strong><em>PRIORITE 2&nbsp;:<\/em><\/strong> exploitant ou un des associ\u00e9s exploitants, install\u00e9 depuis moins de 15 ans.<\/p>\n\n\n\n<p><strong><em>PRIORITE 3&nbsp;:<\/em><\/strong> Priorit\u00e9 \u00e0 l\u2019exploitation qui a le plus petit ratio&nbsp;: SAU d\u00e9clar\u00e9e MSA\/nombre d\u2019exploitant MSA au 01\/03\/2026.<\/p>\n\n\n\n<p><strong><u>Date ultime de remise des offres en mairie de Calvinet&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<p><strong>Lundi 13 avril avant 12h00<\/strong><\/p>\n\n\n\n<p><em><u>Pi\u00e8ces \u00e0 joindre \u00e0 la demande&nbsp;:<\/u><\/em><\/p>\n\n\n\n<p>Attestation d\u2019affiliation de ou des chefs d\u2019exploitation (MSA)<\/p>\n\n\n\n<p>Choix des candidats retenus r\u00e9alis\u00e9 par la commission<\/p>\n\n\n\n<p>Pour tous renseignements&nbsp;: 04.71.49.94.32<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA COMMUNE DE PUYCAPEL Propose 2 lots de vente d\u2019herbe&nbsp;: environ 6 Ha chacun. Un cahier des charges a \u00e9t\u00e9 \u00e9tabli par le conseil municipal&nbsp;: 2 lots disponibles pour 2 exploitations diff\u00e9rentes\/ PRIORITE 1&nbsp;: si\u00e8ge d\u2019exploitation et au moins un des exploitants habitant sur la commune de PUYCAPEL PRIORITE 2&nbsp;: exploitant ou un des associ\u00e9s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-11034","post","type-post","status-publish","format-standard","hentry","category-actuellement"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paADkW-2RY","jetpack-related-posts":[{"id":3888,"url":"https:\/\/puycapel.fr\/index.php\/2021\/04\/19\/vente-dherbe-commune-de-puycapel\/","url_meta":{"origin":11034,"position":0},"title":"VENTE D&rsquo;HERBE &#8211; COMMUNE DE PUYCAPEL","author":"Antoine Puech","date":"19 avril 2021","format":false,"excerpt":"Propose 3 lots de vente d\u2019 herbe: environ 10Ha chacun pour 3 exploitations diff\u00e9rentes : Un cahier des charges a \u00e9t\u00e9 \u00e9tabli par le conseil municipal: PRIORITE 1: si\u00e8ge d ' exploitation et au moins un des exploitants habitant sur la commune de PUYCAPEL. PRIORITE 2:Exploitant ou un des associ\u00e9s\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s&quot;","block_context":{"text":"Actualit\u00e9s","link":"https:\/\/puycapel.fr\/index.php\/category\/actuellement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8581,"url":"https:\/\/puycapel.fr\/index.php\/2023\/11\/09\/vente-des-terres-commune-de-puycapel\/","url_meta":{"origin":11034,"position":1},"title":"\u00a0 Vente des terres commune de PUYCAPEL","author":"Mairie Puycapel","date":"9 novembre 2023","format":false,"excerpt":"Situ\u00e9e sur la commune de PUYCAPEL - secteur Calvinet - en Ch\u00e2taigneraie cantalienne, vends parcelles agricoles pour une contenance de 17 ha 77 a 26 ca r\u00e9partis en 3 lots (photos ci-dessous). Accessibles par la voie d\u00e9partementale ou communale avec diff\u00e9rents points d\u2019eau permanent. Lot 1 : 3 ha 620\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s&quot;","block_context":{"text":"Actualit\u00e9s","link":"https:\/\/puycapel.fr\/index.php\/category\/actuellement\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2023\/11\/ilot-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2023\/11\/ilot-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2023\/11\/ilot-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2023\/11\/ilot-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2023\/11\/ilot-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6112,"url":"https:\/\/puycapel.fr\/index.php\/2021\/12\/02\/atelier-pedagogique-la-fresque-du-climat\/","url_meta":{"origin":11034,"position":2},"title":"Atelier p\u00e9dagogique \u00ab\u00a0la fresque du climat\u00a0\u00bb","author":"Mairie Puycapel","date":"2 d\u00e9cembre 2021","format":false,"excerpt":"Comme une suite \u00e0 la COP26 qui s'est tenue au mois de novembre \u00e0 Glasgow, Boris WAHL propose l'animation d'un atelier p\u00e9dagogique :\u00a0La fresque du climat\u00a0aux habitants de Puycapel. Au del\u00e0 des conviction de chacun, cet atelier vise \u00e0\u00a0apporter\u00a0des connaissances scientifiques sur l'\u00e9volution du climat,\u00a0en priorit\u00e9 aux d\u00e9cideurs (\u00e9lus, chefs\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s&quot;","block_context":{"text":"Actualit\u00e9s","link":"https:\/\/puycapel.fr\/index.php\/category\/actuellement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9329,"url":"https:\/\/puycapel.fr\/index.php\/2024\/07\/22\/collecte-de-pneus\/","url_meta":{"origin":11034,"position":3},"title":"Collecte de pneus","author":"Mairie Puycapel","date":"22 juillet 2024","format":false,"excerpt":"PAR LA FDSEA DU CANTAL Ces derniers mois, de nombreux agriculteurs ont contact\u00e9 la FDSEA du Cantal pour la gestion de leurs pneus usag\u00e9s (principalement utilis\u00e9s sur les silos d\u2019ensilage de ma\u00efs...). Pour r\u00e9pondre \u00e0 cet appel, la FDSEA du Cantal \u00e9tudie la possibilit\u00e9 de proposer une collecte de pneus\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s&quot;","block_context":{"text":"Actualit\u00e9s","link":"https:\/\/puycapel.fr\/index.php\/category\/actuellement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10510,"url":"https:\/\/puycapel.fr\/index.php\/2025\/11\/05\/communaute-de-communes-temps-dechanges\/","url_meta":{"origin":11034,"position":4},"title":"Communaut\u00e9 de communes: temps d&rsquo;\u00e9changes","author":"Mairie Puycapel","date":"5 novembre 2025","format":false,"excerpt":"Dans le cadre de la convention que la Communaut\u00e9 de Communes de la Ch\u00e2taigneraie\u00a0Cantalienne signe avec la CAF et la MSA pour la p\u00e9riode 2026-2031, des temps de rencontres sont organis\u00e9s avec les habitants et acteurs de la vie locale pour \u00e9crire le diagnostic et d\u00e9finir les enjeux. TEMPS D4ECHANGES\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s&quot;","block_context":{"text":"Actualit\u00e9s","link":"https:\/\/puycapel.fr\/index.php\/category\/actuellement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6530,"url":"https:\/\/puycapel.fr\/index.php\/2022\/03\/24\/la-commune-solidaire-avec-lukraine\/","url_meta":{"origin":11034,"position":5},"title":"LA COMMUNE SOLIDAIRE AVEC L\u2019UKRAINE","author":"Mairie Puycapel","date":"24 mars 2022","format":false,"excerpt":"Lors de sa s\u00e9ance du 18 mars, le conseil municipal a d\u00e9cid\u00e9 de la mise \u00e0 disposition d\u2019un logement communal pour accueillir une famille ukrainienne. Ce logement fait l\u2019objet d\u2019un recensement aupr\u00e8s de la Pr\u00e9fecture du Cantal. Celle-ci assurera l\u2019orientation des ressortissants ukrainiens qui arriveront dans le d\u00e9partement, dans des\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s&quot;","block_context":{"text":"Actualit\u00e9s","link":"https:\/\/puycapel.fr\/index.php\/category\/actuellement\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2022\/03\/DRAPEAU.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2022\/03\/DRAPEAU.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2022\/03\/DRAPEAU.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts\/11034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=11034"}],"version-history":[{"count":2,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts\/11034\/revisions"}],"predecessor-version":[{"id":11036,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts\/11034\/revisions\/11036"}],"wp:attachment":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=11034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/categories?post=11034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/tags?post=11034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}