{"id":508,"date":"2019-03-12T16:06:57","date_gmt":"2019-03-12T15:06:57","guid":{"rendered":"https:\/\/puycapel.fr\/?p=508"},"modified":"2019-03-16T16:06:29","modified_gmt":"2019-03-16T15:06:29","slug":"menu-de-la-cantine-de-mourjou","status":"publish","type":"post","link":"https:\/\/puycapel.fr\/index.php\/2019\/03\/12\/menu-de-la-cantine-de-mourjou\/","title":{"rendered":"Menu de la cantine de Mourjou"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"509\" data-permalink=\"https:\/\/puycapel.fr\/index.php\/2019\/03\/12\/menu-de-la-cantine-de-mourjou\/menumourjous11\/\" data-orig-file=\"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?fit=693%2C1041&amp;ssl=1\" data-orig-size=\"693,1041\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"menumourjouS11\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?fit=682%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?fit=682%2C1024&amp;ssl=1\" alt=\"\" class=\"wp-image-509\" width=\"490\" height=\"736\" srcset=\"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?w=693&amp;ssl=1 693w, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?resize=682%2C1024&amp;ssl=1 682w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10,12],"tags":[],"class_list":["post-508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecole","category-menu-de-la-cantine-de-mourjou"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menumourjouS11.jpg?fit=693%2C1041&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paADkW-8c","jetpack-related-posts":[{"id":1023,"url":"https:\/\/puycapel.fr\/index.php\/2019\/05\/20\/menu-cantine-de-mourjou-s-21\/","url_meta":{"origin":508,"position":0},"title":"Menu cantine de Mourjou     du 20 au 24 mai","author":"Mairie Puycapel","date":"20 mai 2019","format":false,"excerpt":"","rel":"","context":"Dans &quot;Commune&quot;","block_context":{"text":"Commune","link":"https:\/\/puycapel.fr\/index.php\/category\/commune\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/05\/cantine-S21-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/05\/cantine-S21-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/05\/cantine-S21-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":944,"url":"https:\/\/puycapel.fr\/index.php\/2019\/05\/06\/menu-de-la-cantine\/","url_meta":{"origin":508,"position":1},"title":"Menu de la cantine","author":"Mairie Puycapel","date":"6 mai 2019","format":false,"excerpt":"cantine scolaire de Mourjou","rel":"","context":"Dans &quot;Ecole&quot;","block_context":{"text":"Ecole","link":"https:\/\/puycapel.fr\/index.php\/category\/commune\/ecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/05\/MENU-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/05\/MENU-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/05\/MENU-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":902,"url":"https:\/\/puycapel.fr\/index.php\/2019\/04\/29\/menu-de-la-cantine-scolaire\/","url_meta":{"origin":508,"position":2},"title":"Menu de la cantine scolaire","author":"Mairie Puycapel","date":"29 avril 2019","format":false,"excerpt":"A l'\u00e9cole de Mourjou -CE2 CM1 CM2","rel":"","context":"Dans &quot;Ecole&quot;","block_context":{"text":"Ecole","link":"https:\/\/puycapel.fr\/index.php\/category\/commune\/ecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/04\/menu-cantine-M.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/04\/menu-cantine-M.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/04\/menu-cantine-M.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1185,"url":"https:\/\/puycapel.fr\/index.php\/2019\/06\/03\/au-menu-de-la-cantine-cette-semaine-2\/","url_meta":{"origin":508,"position":3},"title":"Au menu de la cantine cette semaine","author":"Mairie Puycapel","date":"3 juin 2019","format":false,"excerpt":"Menu de la cantine de Mourjou, semaine 23.","rel":"","context":"Dans &quot;Ecole&quot;","block_context":{"text":"Ecole","link":"https:\/\/puycapel.fr\/index.php\/category\/commune\/ecole\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":798,"url":"https:\/\/puycapel.fr\/index.php\/2019\/04\/08\/au-menu-de-la-cantine\/","url_meta":{"origin":508,"position":4},"title":"Au menu de la cantine","author":"Mairie Puycapel","date":"8 avril 2019","format":false,"excerpt":"Au menu cette semaine \u00e0 la cantine de Mourjou","rel":"","context":"Dans &quot;Commune&quot;","block_context":{"text":"Commune","link":"https:\/\/puycapel.fr\/index.php\/category\/commune\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/04\/menu-s15.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/04\/menu-s15.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/04\/menu-s15.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":688,"url":"https:\/\/puycapel.fr\/index.php\/2019\/03\/18\/menu-de-la-cantine-de-mourjou-2\/","url_meta":{"origin":508,"position":5},"title":"Menu de la cantine de Mourjou","author":"Mairie Puycapel","date":"18 mars 2019","format":false,"excerpt":"","rel":"","context":"Dans &quot;Menu de la cantine de Mourjou&quot;","block_context":{"text":"Menu de la cantine de Mourjou","link":"https:\/\/puycapel.fr\/index.php\/category\/commune\/ecole\/menu-de-la-cantine-de-mourjou\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menu-S12.jpg?fit=673%2C990&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menu-S12.jpg?fit=673%2C990&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/puycapel.fr\/wp-content\/uploads\/2019\/03\/menu-S12.jpg?fit=673%2C990&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":3,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"predecessor-version":[{"id":517,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/posts\/508\/revisions\/517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puycapel.fr\/index.php\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}